{"id":198,"date":"2022-05-31T03:05:15","date_gmt":"2022-05-31T03:05:15","guid":{"rendered":"http:\/\/woocommerce.template.dev.elionter.net\/wishlist\/"},"modified":"2022-06-07T04:24:07","modified_gmt":"2022-06-07T04:24:07","slug":"wishlist","status":"publish","type":"page","link":"https:\/\/woocommerce.template.dev.elionter.net\/fr\/wishlist\/","title":{"rendered":"Wishlist"},"content":{"rendered":"<div data-elementor-type=\"wp-page\" data-elementor-id=\"198\" class=\"elementor elementor-198\">\n\t\t\t\t\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-72d35c33 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"72d35c33\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-109e2cb4\" data-id=\"109e2cb4\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-element elementor-element-a5b1d60 elementor-view-default elementor-widget elementor-widget-icon\" data-id=\"a5b1d60\" data-element_type=\"widget\" data-widget_type=\"icon.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-icon-wrapper\">\n\t\t\t<div class=\"elementor-icon\">\n\t\t\t<i aria-hidden=\"true\" class=\"far fa-heart\"><\/i>\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-e571eff elementor-widget elementor-widget-heading\" data-id=\"e571eff\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<style>\/*! elementor - v3.6.5 - 27-04-2022 *\/\n.elementor-heading-title{padding:0;margin:0;line-height:1}.elementor-widget-heading .elementor-heading-title[class*=elementor-size-]>a{color:inherit;font-size:inherit;line-height:inherit}.elementor-widget-heading .elementor-heading-title.elementor-size-small{font-size:15px}.elementor-widget-heading .elementor-heading-title.elementor-size-medium{font-size:19px}.elementor-widget-heading .elementor-heading-title.elementor-size-large{font-size:29px}.elementor-widget-heading .elementor-heading-title.elementor-size-xl{font-size:39px}.elementor-widget-heading .elementor-heading-title.elementor-size-xxl{font-size:59px}<\/style><h1 class=\"elementor-heading-title elementor-size-default\">My Wishlist<\/h1>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-f30c621 elementor-widget elementor-widget-text-editor\" data-id=\"f30c621\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<style>\/*! elementor - v3.6.5 - 27-04-2022 *\/\n.elementor-widget-text-editor.elementor-drop-cap-view-stacked .elementor-drop-cap{background-color:#818a91;color:#fff}.elementor-widget-text-editor.elementor-drop-cap-view-framed .elementor-drop-cap{color:#818a91;border:3px solid;background-color:transparent}.elementor-widget-text-editor:not(.elementor-drop-cap-view-default) .elementor-drop-cap{margin-top:8px}.elementor-widget-text-editor:not(.elementor-drop-cap-view-default) .elementor-drop-cap-letter{width:1em;height:1em}.elementor-widget-text-editor .elementor-drop-cap{float:left;text-align:center;line-height:1;font-size:50px}.elementor-widget-text-editor .elementor-drop-cap-letter{display:inline-block}<\/style>\t\t\t\t<p><div class=\"tinv-wishlist woocommerce\">\n\t<div class=\"tinv-header\">\n\t<h2><\/h2>\n\t<\/div>\n\t\t<p class=\"cart-empty woocommerce-info\">\n\t\t\t\t\tVotre liste de souhaits est vide.\t\t\t<\/p>\n\n\t\n\t<p class=\"return-to-shop\">\n\t\t<a class=\"button wc-backward\"\n\t\t   href=\"https:\/\/woocommerce.template.dev.elionter.net\/fr\/shop\/\">Retour \u00e0 la boutique<\/a>\n\t<\/p>\n<\/div>\n<\/p>\r\n<!-- wp:shortcode --><!-- \/wp:shortcode -->\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t\t\t<\/div>","protected":false},"excerpt":{"rendered":"<p>My Wishlist<\/p>","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":[],"_links":{"self":[{"href":"https:\/\/woocommerce.template.dev.elionter.net\/fr\/wp-json\/wp\/v2\/pages\/198"}],"collection":[{"href":"https:\/\/woocommerce.template.dev.elionter.net\/fr\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/woocommerce.template.dev.elionter.net\/fr\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/woocommerce.template.dev.elionter.net\/fr\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/woocommerce.template.dev.elionter.net\/fr\/wp-json\/wp\/v2\/comments?post=198"}],"version-history":[{"count":17,"href":"https:\/\/woocommerce.template.dev.elionter.net\/fr\/wp-json\/wp\/v2\/pages\/198\/revisions"}],"predecessor-version":[{"id":1029,"href":"https:\/\/woocommerce.template.dev.elionter.net\/fr\/wp-json\/wp\/v2\/pages\/198\/revisions\/1029"}],"wp:attachment":[{"href":"https:\/\/woocommerce.template.dev.elionter.net\/fr\/wp-json\/wp\/v2\/media?parent=198"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}